{"id":8143,"date":"2026-07-01T10:02:57","date_gmt":"2026-07-01T08:02:57","guid":{"rendered":"https:\/\/www.hplatjadaro.com\/quienes-somos-2\/"},"modified":"2026-08-27T11:29:26","modified_gmt":"2026-08-27T09:29:26","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/","title":{"rendered":"Qui\u00e9nes somos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8143\" class=\"elementor elementor-8143 elementor-8142\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cef9931 e-con-full e-flex e-con e-parent\" data-id=\"cef9931\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e45a6d8 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"e45a6d8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t<div class=\"elementor-element elementor-element-97944ae e-con-full e-flex e-con e-child\" data-id=\"97944ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-973ab3b elementor-widget elementor-widget-image\" data-id=\"973ab3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"17\" src=\"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2023\/05\/icon-blanc.svg\" class=\"attachment-large size-large wp-image-6004\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-955fa91 elementor-widget elementor-widget-heading\" data-id=\"955fa91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00a1Bienvenidos al Hotel Platja d'Aro!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef8874 elementor-widget elementor-widget-text-editor\" data-id=\"aef8874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Si hab\u00e9is llegado hasta aqu\u00ed es porque nos hab\u00e9is buscado, alguien os lo ha recomendado o, simplemente, el destino os ha tra\u00eddo hasta nosotros. Ya que est\u00e1is aqu\u00ed, os invitamos a aprovechar la ocasi\u00f3n para conocer qui\u00e9nes somos.<\/p><p class=\"p1\">Somos un hotel familiar y para grupos, situado justo en el centro de ocio de Platja d&#8217;Aro y junto a la playa. Nuestra ubicaci\u00f3n, a 5 minutos a pie de la playa y del centro, y a 3 minutos de la zona comercial y de ocio con cines, bolera, tiendas y supermercados, convierte este emplazamiento en una de nuestras se\u00f1as de identidad.<\/p><p class=\"p1\">Contamos con 40 habitaciones y un apartamento, totalmente climatizados, la mayor\u00eda con amplias terrazas y vistas a la monta\u00f1a o al mar, pensadas tanto para alojar a familias como a grupos, con habitaciones de hasta 5 camas fijas. Disponemos tambi\u00e9n de una gran piscina exterior rodeada de c\u00e9sped natural, de un servicio de bufet de desayuno incluido en el precio del alojamiento, y de parking exterior gratuito, para hacer m\u00e1s completa la estancia de nuestros hu\u00e9spedes. Y si viaj\u00e1is con vuestra mascota, no os preocup\u00e9is: todas las habitaciones la admiten.<\/p><p class=\"p1\">Estar en el centro de ocio de Platja d&#8217;Aro nos permite ofreceros la cercan\u00eda a una de las ofertas comerciales, de ocio y de actividades deportivas, culturales y de convenciones m\u00e1s ricas de la Costa Brava, con todo lo que necesit\u00e9is al alcance de la mano.<\/p><p class=\"p1\">Todo lo que hacemos est\u00e1 orientado al bienestar de nuestros clientes: desde la experiencia (m\u00e1s de 60 a\u00f1os avalan nuestra trayectoria recibiendo viajeros), <b>el trato <\/b>(sirviendo al cliente de forma amable y respetuosa, buscando que la experiencia en el hotel os resulte estimulante para volver), <b>el compromiso <\/b>(de todo nuestro equipo hacia el hotel y hacia el cliente, aportando valor y superando expectativas) y, en clave interna, el orgullo de pertenencia; formamos parte de <b>Aromar Hotels &amp; Restaurants<\/b>, una compa\u00f1\u00eda pionera del turismo en la Costa Brava, con un proyecto s\u00f3lido y en constante renovaci\u00f3n.<\/p><p class=\"p1\">Nos gustar\u00e1 mucho saludaros personalmente, si tenemos ocasi\u00f3n. Y, sobre todo, esperamos que vuestra experiencia con nosotros os resulte m\u00e1s que satisfactoria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0782342 e-con-full e-flex e-con e-child\" data-id=\"0782342\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4cbbaa elementor-widget elementor-widget-image\" data-id=\"f4cbbaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"461\" height=\"567\" src=\"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/carme-hospital.png\" class=\"attachment-full size-full wp-image-8591\" alt=\"\" srcset=\"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/carme-hospital.png 461w, https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/carme-hospital-244x300.png 244w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c605a0b e-flex e-con-boxed e-con e-child\" data-id=\"c605a0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-141a288 elementor-widget elementor-widget-heading\" data-id=\"141a288\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Carme Hospital Poch\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-807df72 elementor-widget elementor-widget-heading\" data-id=\"807df72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Presidenta de Aromar Hotels &amp; Restaurants\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9f5290 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"e9f5290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/youtu.be\\\/uSThul6CQF4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_video_start&quot;:81,&quot;background_video_end&quot;:97}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95e07d5 e-con-full e-flex e-con e-parent\" data-id=\"95e07d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b71d65 elementor-widget elementor-widget-template\" data-id=\"3b71d65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"8693\" class=\"elementor elementor-8693 elementor-8470 elementor-8470\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebc97e7 e-flex e-con-boxed e-con e-parent\" data-id=\"ebc97e7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd8ca21 elementor-widget elementor-widget-heading\" data-id=\"6cd8ca21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Ventajas de reservar en la web<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd9042e e-con-full e-flex e-con e-child\" data-id=\"fd9042e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-636cc431 elementor-widget-mobile__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"636cc431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#000000\"><path d=\"M444.5-164.5Q430-179 430-200t14.5-35.5Q459-250 480-250t35.5 14.5Q530-221 530-200t-14.5 35.5Q501-150 480-150t-35.5-14.5ZM254-346l-28-28q50-50 114.5-78T480-480q75 0 139.5 28T734-374l-28 28q-44-44-102-69t-124-25q-66 0-124 25t-102 69ZM84-516l-28-28q81-81 189-128.5T480-720q127 0 235 47.5T904-544l-28 28q-77-77-178.5-120.5T480-680q-116 0-217.5 43.5T84-516Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWi-Fi gratis\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-327e8bff elementor-widget-mobile__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"327e8bff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#000000\"><path d=\"M192-132q-26 0-43-17t-17-43v-576q0-26 17-43t43-17h576q26 0 43 17t17 43v576q0 26-17 43t-43 17H192Zm0-28h576q12 0 22-10t10-22v-576q0-12-10-22t-22-10H192q-12 0-22 10t-10 22v576q0 12 10 22t22 10Zm128.5-260.5Q312-429 312-440t8.5-19.5Q329-468 340-468t19.5 8.5Q368-451 368-440t-8.5 19.5Q351-412 340-412t-19.5-8.5Zm280 0Q592-429 592-440t8.5-19.5Q609-468 620-468t19.5 8.5Q648-451 648-440t-8.5 19.5Q631-412 620-412t-19.5-8.5ZM252-508v222q0 6 4 10t10 4q6 0 10-4t4-10v-66h400v66q0 6 4 10t10 4q6 0 10-4t4-10v-222l-58-166q-2-7-7.5-10.5T630-688H330q-7 0-12.5 3.5T310-674l-58 166Zm36-20 46-132h292l46 132H288ZM160-800v640-640Zm120 420v-120h400v120H280Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tParking gratis\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-846c732 elementor-widget-mobile__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"846c732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#000000\"><path d=\"m354-287 126-76 126 77-33-144 111-96-146-13-58-136-58 135-146 13 111 97-33 143Zm-43 59 45-192-149-129 196-17 77-181 77 181 196 17-149 129 45 192-169-102-169 102Zm169-242Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCheck-in\/out flexible\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13300eda elementor-widget-mobile__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"13300eda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#000000\"><path d=\"M828-688v416q0 26-17 43t-43 17H192q-26 0-43-17t-17-43v-416q0-26 17-43t43-17h576q26 0 43 17t17 43Zm-668 90h640v-90q0-12-10-22t-22-10H192q-12 0-22 10t-10 22v90Zm0 76v250q0 12 10 22t22 10h576q12 0 22-10t10-22v-250H160Zm0 282v-480 480Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPago en el hotel\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00a1Bienvenidos al Hotel Platja d&#8217;Aro! Si hab\u00e9is llegado hasta aqu\u00ed es porque nos hab\u00e9is buscado, alguien os lo ha recomendado o, simplemente, el destino os ha tra\u00eddo hasta nosotros. Ya que est\u00e1is aqu\u00ed, os invitamos a aprovechar la ocasi\u00f3n para conocer qui\u00e9nes somos. Somos un hotel familiar y para grupos, situado justo en el centro&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"class_list":["post-8143","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui\u00e9nes somos | Hotel Platja d&#039;Aro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9nes somos | Hotel Platja d&#039;Aro\" \/>\n<meta property=\"og:description\" content=\"\u00a1Bienvenidos al Hotel Platja d&#8217;Aro! Si hab\u00e9is llegado hasta aqu\u00ed es porque nos hab\u00e9is buscado, alguien os lo ha recomendado o, simplemente, el destino os ha tra\u00eddo hasta nosotros. Ya que est\u00e1is aqu\u00ed, os invitamos a aprovechar la ocasi\u00f3n para conocer qui\u00e9nes somos. Somos un hotel familiar y para grupos, situado justo en el centro&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Platja d&#039;Aro\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T09:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2024\/04\/Aromar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/\",\"name\":\"Qui\u00e9nes somos | Hotel Platja d&#039;Aro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/icon-blanc.svg\",\"datePublished\":\"2026-07-01T08:02:57+00:00\",\"dateModified\":\"2026-08-27T09:29:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/icon-blanc.svg\",\"contentUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/icon-blanc.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/quienes-somos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9nes somos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/\",\"name\":\"Aromar Hotels & Restaurants\",\"description\":\"Hotel familiar a Platja d&#039;Aro, Costa Brava\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#organization\"},\"alternateName\":\"Aromar Hotels & Restaurants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#organization\",\"name\":\"Hotel Platja d'Aro\",\"alternateName\":\"Aromar Hotels\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Aromar-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Aromar-2.jpg\",\"width\":696,\"height\":696,\"caption\":\"Hotel Platja d'Aro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9nes somos | Hotel Platja d&#039;Aro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9nes somos | Hotel Platja d&#039;Aro","og_description":"\u00a1Bienvenidos al Hotel Platja d&#8217;Aro! Si hab\u00e9is llegado hasta aqu\u00ed es porque nos hab\u00e9is buscado, alguien os lo ha recomendado o, simplemente, el destino os ha tra\u00eddo hasta nosotros. Ya que est\u00e1is aqu\u00ed, os invitamos a aprovechar la ocasi\u00f3n para conocer qui\u00e9nes somos. Somos un hotel familiar y para grupos, situado justo en el centro&hellip;&nbsp;","og_url":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/","og_site_name":"Hotel Platja d&#039;Aro","article_modified_time":"2026-08-27T09:29:26+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2024\/04\/Aromar.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/","url":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/","name":"Qui\u00e9nes somos | Hotel Platja d&#039;Aro","isPartOf":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/#primaryimage"},"image":{"@id":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2023\/05\/icon-blanc.svg","datePublished":"2026-07-01T08:02:57+00:00","dateModified":"2026-08-27T09:29:26+00:00","breadcrumb":{"@id":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/#primaryimage","url":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2023\/05\/icon-blanc.svg","contentUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2023\/05\/icon-blanc.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hplatjadaro.com\/es\/quienes-somos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hplatjadaro.com\/es\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9nes somos"}]},{"@type":"WebSite","@id":"https:\/\/www.hplatjadaro.com\/es\/#website","url":"https:\/\/www.hplatjadaro.com\/es\/","name":"Aromar Hotels & Restaurants","description":"Hotel familiar a Platja d&#039;Aro, Costa Brava","publisher":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#organization"},"alternateName":"Aromar Hotels & Restaurants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hplatjadaro.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hplatjadaro.com\/es\/#organization","name":"Hotel Platja d'Aro","alternateName":"Aromar Hotels","url":"https:\/\/www.hplatjadaro.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hplatjadaro.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2024\/04\/Aromar-2.jpg","contentUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2024\/04\/Aromar-2.jpg","width":696,"height":696,"caption":"Hotel Platja d'Aro"},"image":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/pages\/8143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/comments?post=8143"}],"version-history":[{"count":7,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/pages\/8143\/revisions"}],"predecessor-version":[{"id":9627,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/pages\/8143\/revisions\/9627"}],"wp:attachment":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/media?parent=8143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}