{"id":8266,"date":"2026-07-02T10:35:24","date_gmt":"2026-07-02T08:35:24","guid":{"rendered":"https:\/\/www.hplatjadaro.com\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/"},"modified":"2026-07-14T11:14:19","modified_gmt":"2026-07-14T09:14:19","slug":"els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2","status":"publish","type":"post","link":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/","title":{"rendered":"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente"},"content":{"rendered":"<p class=\"p1\"><em>Repasamos los jardines bot\u00e1nicos que puedes visitar durante tu estancia en Platja d&#8217;Aro<\/em><\/p>\n<p class=\"p1\">Las grandes bondades que tiene la Costa Brava muchas veces ocasionan que algunos lugares pasen casi completamente desapercibidos a pesar de ser planes maravillosos para pasar en pareja, en familia o incluso con amigos.<\/p>\n<p class=\"p1\">Uno de los secretos que esconde son los jardines bot\u00e1nicos. El Hotel Platja d&#8217;Aro est\u00e1 situado en una <strong>ubicaci\u00f3n inmejorable<\/strong>: playa, centro comercial, supermercados, tiendas, etc. Una partida a los bolos, ir a la playa, el estreno de una pel\u00edcula, practicar deporte, comer un helado, hacer submarinismo o ir de compras son actividades recurrentes que tenemos a nuestro alcance m\u00e1s inmediato, pero \u00bfpor qu\u00e9 no decir que s\u00ed a un plan completamente diferente?<\/p>\n<p class=\"p1\">Platja d&#8217;Aro es un municipio abierto a todo tipo de turismo y un destino tur\u00edstico familiar certificado. Hay espacio para todo y para todos.<\/p>\n<p class=\"p1\">Los amantes de la tranquilidad, la naturaleza viva y la imaginaci\u00f3n tienen en la Costa Brava <strong>cuatro jardines bot\u00e1nicos<\/strong> que no se pueden perder. Son lugares ideales para aprender sobre \u00e1rboles y plantas de toda clase. \u00bfNo sabes cu\u00e1les son?<\/p>\n<h2 class=\"p1\">Jard\u00edn Bot\u00e1nico Marimurtra<\/h2>\n<p class=\"p1\">Cinco hect\u00e1reas y fuertes desniveles entre multitud de escaleras y senderos. Se encuentra en Blanes, el primer pueblo de la Costa Brava. No solo es una atracci\u00f3n tur\u00edstica, sino que tambi\u00e9n es un importante centro de investigaci\u00f3n en bot\u00e1nica y biolog\u00eda.<\/p>\n<h2 class=\"p1\">Jardines bot\u00e1nicos de Cap Roig<\/h2>\n<p class=\"p1\">En Calella de Palafrugell te esperan m\u00e1s de mil especies bot\u00e1nicas procedentes de todos los lugares del mundo, adem\u00e1s de un buen n\u00famero de esculturas de artistas reconocidos mundialmente.<\/p>\n<h2 class=\"p1\">Jardines de Santa Clotilde<\/h2>\n<p class=\"p1\">Estos jardines novecentistas se sit\u00faan en Lloret de Mar, en un acantilado con unas vistas espectaculares al mar. Fueron dise\u00f1ados en 1919 con una clara influencia italiana y creando una combinaci\u00f3n armoniosa con la obra arquitect\u00f3nica del entorno.<\/p>\n<h2 class=\"p1\">Jard\u00edn bot\u00e1nico Pinya de Rosa<\/h2>\n<p class=\"p1\">Entre Blanes y Lloret de Mar este jard\u00edn te hace sentir como en el tr\u00f3pico. Tiene cincuenta hect\u00e1reas de vegetaci\u00f3n aut\u00f3ctona con la peculiaridad de haber adaptado especies vegetales caracter\u00edsticas de los tr\u00f3picos en un entorno mediterr\u00e1neo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Repasamos los jardines bot\u00e1nicos que puedes visitar durante tu estancia en Platja d&#8217;Aro Las grandes bondades que tiene la Costa Brava muchas veces ocasionan que algunos lugares pasen casi completamente desapercibidos a pesar de ser planes maravillosos para pasar en pareja, en familia o incluso con amigos. Uno de los secretos que esconde son los&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":8248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"categories":[82],"tags":[],"class_list":["post-8266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente | Hotel Platja d&#039;Aro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente | Hotel Platja d&#039;Aro\" \/>\n<meta property=\"og:description\" content=\"Repasamos los jardines bot\u00e1nicos que puedes visitar durante tu estancia en Platja d&#8217;Aro Las grandes bondades que tiene la Costa Brava muchas veces ocasionan que algunos lugares pasen casi completamente desapercibidos a pesar de ser planes maravillosos para pasar en pareja, en familia o incluso con amigos. Uno de los secretos que esconde son los&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Platja d&#039;Aro\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-02T08:35:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T09:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicaci\u00f3 Integral Neorg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicaci\u00f3 Integral Neorg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/\"},\"author\":{\"name\":\"Comunicaci\u00f3 Integral Neorg\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#\\\/schema\\\/person\\\/3b4dad233a49ff0bc5b42d830b3f7e53\"},\"headline\":\"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente\",\"datePublished\":\"2026-07-02T08:35:24+00:00\",\"dateModified\":\"2026-07-14T09:14:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/\",\"name\":\"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente | Hotel Platja d&#039;Aro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg\",\"datePublished\":\"2026-07-02T08:35:24+00:00\",\"dateModified\":\"2026-07-14T09:14:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg\",\"width\":1024,\"height\":653},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/\",\"name\":\"Aromar Hotels & Restaurants\",\"description\":\"Hotel familiar a Platja d&#039;Aro, Costa Brava\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#organization\"},\"alternateName\":\"Aromar Hotels & Restaurants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#organization\",\"name\":\"Hotel Platja d'Aro\",\"alternateName\":\"Aromar Hotels\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Aromar-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hplatjadaro.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Aromar-2.jpg\",\"width\":696,\"height\":696,\"caption\":\"Hotel Platja d'Aro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hplatjadaro.com\\\/es\\\/#\\\/schema\\\/person\\\/3b4dad233a49ff0bc5b42d830b3f7e53\",\"name\":\"Comunicaci\u00f3 Integral Neorg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/709d3d8015183afa7401c02e2291a538cbfd4ffe62f4d86ce5f4871f22e86b09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/709d3d8015183afa7401c02e2291a538cbfd4ffe62f4d86ce5f4871f22e86b09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/709d3d8015183afa7401c02e2291a538cbfd4ffe62f4d86ce5f4871f22e86b09?s=96&d=mm&r=g\",\"caption\":\"Comunicaci\u00f3 Integral Neorg\"},\"sameAs\":[\"https:\\\/\\\/www.hplatjadaro.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente | Hotel Platja d&#039;Aro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/","og_locale":"es_ES","og_type":"article","og_title":"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente | Hotel Platja d&#039;Aro","og_description":"Repasamos los jardines bot\u00e1nicos que puedes visitar durante tu estancia en Platja d&#8217;Aro Las grandes bondades que tiene la Costa Brava muchas veces ocasionan que algunos lugares pasen casi completamente desapercibidos a pesar de ser planes maravillosos para pasar en pareja, en familia o incluso con amigos. Uno de los secretos que esconde son los&hellip;&nbsp;","og_url":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/","og_site_name":"Hotel Platja d&#039;Aro","article_published_time":"2026-07-02T08:35:24+00:00","article_modified_time":"2026-07-14T09:14:19+00:00","og_image":[{"width":1024,"height":653,"url":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg","type":"image\/jpeg"}],"author":"Comunicaci\u00f3 Integral Neorg","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Comunicaci\u00f3 Integral Neorg","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#article","isPartOf":{"@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/"},"author":{"name":"Comunicaci\u00f3 Integral Neorg","@id":"https:\/\/www.hplatjadaro.com\/es\/#\/schema\/person\/3b4dad233a49ff0bc5b42d830b3f7e53"},"headline":"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente","datePublished":"2026-07-02T08:35:24+00:00","dateModified":"2026-07-14T09:14:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/"},"wordCount":398,"publisher":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#organization"},"image":{"@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg","articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/","url":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/","name":"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente | Hotel Platja d&#039;Aro","isPartOf":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#primaryimage"},"image":{"@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg","datePublished":"2026-07-02T08:35:24+00:00","dateModified":"2026-07-14T09:14:19+00:00","breadcrumb":{"@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#primaryimage","url":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg","contentUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2026\/07\/FILES_ITEMS_584_JARDINES_W_1900_Q_100.jpg","width":1024,"height":653},{"@type":"BreadcrumbList","@id":"https:\/\/www.hplatjadaro.com\/es\/els-jardins-botanics-de-la-costa-brava-que-et-sorprendran-totalment-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hplatjadaro.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los jardines bot\u00e1nicos de la Costa Brava que te sorprender\u00e1n totalmente"}]},{"@type":"WebSite","@id":"https:\/\/www.hplatjadaro.com\/es\/#website","url":"https:\/\/www.hplatjadaro.com\/es\/","name":"Aromar Hotels & Restaurants","description":"Hotel familiar a Platja d&#039;Aro, Costa Brava","publisher":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#organization"},"alternateName":"Aromar Hotels & Restaurants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hplatjadaro.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.hplatjadaro.com\/es\/#organization","name":"Hotel Platja d'Aro","alternateName":"Aromar Hotels","url":"https:\/\/www.hplatjadaro.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.hplatjadaro.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2024\/04\/Aromar-2.jpg","contentUrl":"https:\/\/www.hplatjadaro.com\/wp-content\/uploads\/2024\/04\/Aromar-2.jpg","width":696,"height":696,"caption":"Hotel Platja d'Aro"},"image":{"@id":"https:\/\/www.hplatjadaro.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hplatjadaro.com\/es\/#\/schema\/person\/3b4dad233a49ff0bc5b42d830b3f7e53","name":"Comunicaci\u00f3 Integral Neorg","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/709d3d8015183afa7401c02e2291a538cbfd4ffe62f4d86ce5f4871f22e86b09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/709d3d8015183afa7401c02e2291a538cbfd4ffe62f4d86ce5f4871f22e86b09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/709d3d8015183afa7401c02e2291a538cbfd4ffe62f4d86ce5f4871f22e86b09?s=96&d=mm&r=g","caption":"Comunicaci\u00f3 Integral Neorg"},"sameAs":["https:\/\/www.hplatjadaro.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/posts\/8266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/comments?post=8266"}],"version-history":[{"count":1,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/posts\/8266\/revisions"}],"predecessor-version":[{"id":8890,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/posts\/8266\/revisions\/8890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/media\/8248"}],"wp:attachment":[{"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/media?parent=8266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/categories?post=8266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hplatjadaro.com\/es\/wp-json\/wp\/v2\/tags?post=8266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}